{"id":2523,"date":"2026-01-31T16:38:02","date_gmt":"2026-01-31T15:38:02","guid":{"rendered":"https:\/\/saintbenoit86.fr\/wordpress\/events\/exposition-de-veronique-bernier\/"},"modified":"2026-03-19T13:57:11","modified_gmt":"2026-03-19T12:57:11","slug":"exposition-de-veronique-bernier","status":"publish","type":"lsvr_event","link":"https:\/\/saintbenoit86.fr\/wordpress\/events\/exposition-de-veronique-bernier\/","title":{"rendered":"Exposition de V\u00e9ronique Bernier"},"content":{"rendered":"\n<p>\u00abFruit d\u2019un travail solitaire ou bien d\u2019une collaboration in\u00e9dite, les expressions artistiques mises en sc\u00e8ne ont pour particularit\u00e9 de m\u00ealer les mat\u00e9riaux: \u00e9mail, terre c\u00f4toient l\u2019acrylique, l\u2019huile, le pastel ou le sable.<\/p>\n\n\n\n<p>Les savoir-faire s\u2019imbriquent et se compl\u00e8tent au travers d\u2019\u0153uvres singuli\u00e8res. Si les inspirations sont multiples, le point de d\u00e9part reste toujours le m\u00eame: la mati\u00e8re.L\u2019exposition t\u00e9moigne d\u2019une multidisciplinarit\u00e9 de techniques entrant en r\u00e9sonance.\u00bb<\/p>\n\n\n\n<p>Entr\u00e9e gratuite<br>Aux heures d\u2019ouverture du l\u2019Office du Tourisme: du mardi au vendredi, de 9h \u00e0 12h30 et de 13h30 \u00e0 18h<br>et samedi de 9h \u00e0 13h.<br>Pr\u00e9sence de l\u2019artiste du lundi au dimanche de 10h \u00e0 12h30 et de 14h30 \u00e0 18h.<br>Renseignements : l\u2019Office de tourisme de Saint-Beno\u00eet \/ Grand Poitiers : <a href=\"tel:0549474453\" class=\"phone-autolink\">05 49 47 44 53<\/a> \u2013 tourisme@saint-benoit86.fr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abFruit d\u2019un travail solitaire ou bien d\u2019une collaboration in\u00e9dite, les expressions artistiques mises en sc\u00e8ne ont pour particularit\u00e9 de m\u00ealer les mat\u00e9riaux: \u00e9mail, terre c\u00f4toient l\u2019acrylique, l\u2019huile, le pastel ou le sable. Les savoir-faire s\u2019imbriquent et se compl\u00e8tent au travers d\u2019\u0153uvres singuli\u00e8res. Si les inspirations sont multiples, le point de d\u00e9part reste toujours le m\u00eame: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3794,"template":"","meta":{"_acf_changed":false,"footnotes":""},"lsvr_event_cat":[234],"lsvr_event_tag":[],"class_list":["post-2523","lsvr_event","type-lsvr_event","status-publish","has-post-thumbnail","hentry","lsvr_event_location-dortoir-des-moines","lsvr_event_cat-exposition"],"acf":[],"_links":{"self":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_event\/2523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_event"}],"about":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/types\/lsvr_event"}],"author":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_event\/2523\/revisions"}],"predecessor-version":[{"id":3795,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_event\/2523\/revisions\/3795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media\/3794"}],"wp:attachment":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2523"}],"wp:term":[{"taxonomy":"lsvr_event_cat","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_event_cat?post=2523"},{"taxonomy":"lsvr_event_tag","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_event_tag?post=2523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}