{"id":2728,"date":"2026-02-16T14:21:28","date_gmt":"2026-02-16T13:21:28","guid":{"rendered":"https:\/\/saintbenoit86.fr\/wordpress\/directory\/couture-creation\/"},"modified":"2026-02-16T14:21:28","modified_gmt":"2026-02-16T13:21:28","slug":"couture-creation","status":"publish","type":"lsvr_listing","link":"https:\/\/saintbenoit86.fr\/wordpress\/directory\/couture-creation\/","title":{"rendered":"COUTURE CREATION"},"content":{"rendered":"<p>Les cours ont lieu salle Jacques Pr\u00e9vert, Foyer Val du Clain, rue de Mauroc  les mardis de 14h \u00e0 17h et de 17h30 \u00e0 20h30 ainsi que les jeudis de 14h \u00e0 17h et de 17h30 \u00e0 20h30.<\/p>\n<p>D\u00e9butants ou experts, vous serez conseill\u00e9s par une animatrice, couturi\u00e8re de m\u00e9tier<\/p>\n<p>L\u2019association met \u00e0 votre disposition des machines \u00e0 coudre, surjeteuses, fers et tables \u00e0 repasser, patrons et catalogues de mode, mannequins etc\u2026..<\/p>\n<p>Un cours d\u2019essai est possible sur demande. Contactez l\u2019association afin de connaitre les modalit\u00e9s d\u2019inscription.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les cours ont lieu salle Jacques Pr\u00e9vert, Foyer Val du Clain, rue de Mauroc les mardis de 14h \u00e0 17h et de 17h30 \u00e0 20h30 ainsi que les jeudis de 14h \u00e0 17h et de 17h30 \u00e0 20h30. D\u00e9butants ou experts, vous serez conseill\u00e9s par une animatrice, couturi\u00e8re de m\u00e9tier L\u2019association met \u00e0 votre disposition [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"lsvr_listing_cat":[201],"lsvr_listing_tag":[],"class_list":["post-2728","lsvr_listing","type-lsvr_listing","status-publish","hentry","lsvr_listing_cat-loisirs"],"acf":[],"_links":{"self":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing"}],"about":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/types\/lsvr_listing"}],"author":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing\/2728\/revisions"}],"wp:attachment":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2728"}],"wp:term":[{"taxonomy":"lsvr_listing_cat","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing_cat?post=2728"},{"taxonomy":"lsvr_listing_tag","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing_tag?post=2728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}