{"id":2800,"date":"2026-02-16T14:21:37","date_gmt":"2026-02-16T13:21:37","guid":{"rendered":"https:\/\/saintbenoit86.fr\/wordpress\/directory\/ultramical86\/"},"modified":"2026-02-16T14:21:37","modified_gmt":"2026-02-16T13:21:37","slug":"ultramical86","status":"publish","type":"lsvr_listing","link":"https:\/\/saintbenoit86.fr\/wordpress\/directory\/ultramical86\/","title":{"rendered":"Ultramical86"},"content":{"rendered":"<p>Ultramical86 :<\/p>\n<p>des pratiquants de course \u00e0 pied \u00ab\u00a0hors stade\u00a0\u00bb, tout type, tout niveau, toute distance.<br \/>\ndes s\u00e9ances de renforcement, des entra\u00eenements r\u00e9fl\u00e9chis sur piste, des sorties urbaines et natures sur Saint Benoit, Poitiers et les environs.<br \/>\ndes d\u00e9placements sur les courses locales, nationales, voire internationales.<br \/>\ndes week-ends pour pr\u00e9parer des Ultras ou pour partager le plaisir de courir.<br \/>\ndes manifestations sportives (Off 1000 marches, Challenge 732) qui allient d\u00e9fi sportif et convivialit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultramical86 : des pratiquants de course \u00e0 pied \u00ab\u00a0hors stade\u00a0\u00bb, tout type, tout niveau, toute distance. des s\u00e9ances de renforcement, des entra\u00eenements r\u00e9fl\u00e9chis sur piste, des sorties urbaines et natures sur Saint Benoit, Poitiers et les environs. des d\u00e9placements sur les courses locales, nationales, voire internationales. des week-ends pour pr\u00e9parer des Ultras ou pour partager [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"lsvr_listing_cat":[203],"lsvr_listing_tag":[],"class_list":["post-2800","lsvr_listing","type-lsvr_listing","status-publish","hentry","lsvr_listing_cat-sport"],"acf":[],"_links":{"self":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing\/2800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing"}],"about":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/types\/lsvr_listing"}],"author":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing\/2800\/revisions"}],"wp:attachment":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2800"}],"wp:term":[{"taxonomy":"lsvr_listing_cat","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing_cat?post=2800"},{"taxonomy":"lsvr_listing_tag","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/lsvr_listing_tag?post=2800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}