{"id":3898,"date":"2026-03-25T14:16:04","date_gmt":"2026-03-25T13:16:04","guid":{"rendered":"https:\/\/saintbenoit86.fr\/wordpress\/le-nouveau-conseil-municipal-prend-ses-fonctions\/"},"modified":"2026-04-26T21:42:44","modified_gmt":"2026-04-26T19:42:44","slug":"le-nouveau-conseil-municipal-prend-ses-fonctions","status":"publish","type":"post","link":"https:\/\/saintbenoit86.fr\/wordpress\/le-nouveau-conseil-municipal-prend-ses-fonctions\/","title":{"rendered":"Le nouveau Conseil Municipal prend ses fonctions."},"content":{"rendered":"<p><em>\u00ab\u00a0Ensemble, nous allons \u00e9crire une nouvelle et belle page de l\u2019histoire de notre commune.\u00a0\u00bb<\/em><\/p>\n<p>D<strong>imanche 22 mars <\/strong>2026, le nouveau Conseil Municipal s\u2019est officiellement install\u00e9.\u00a0<strong><em>M. Hubert Bailly<\/em><\/strong> a \u00e9t\u00e9 \u00e9lu <strong>maire de la commune de Saint-Beno\u00eet<\/strong>.<br \/>\nHuit adjoints, onze d\u00e9l\u00e9gu\u00e9s et neuf conseillers municipaux\u00a0se sont engag\u00e9s pour l\u2019\u00e9pauler dans la conduite des projets de la commune.<\/p>\n<p>Le<strong> <\/strong>nouveau Maire<strong> remercie <\/strong>tous les sancto-b\u00e9n\u00e9dictins<strong> <\/strong>et sancto-b\u00e9n\u00e9dictines<strong> <\/strong>qui ont assum\u00e9 leur engagement citoyen ainsi que ceux qui ne se sont pas exprim\u00e9s, car tous les <strong>habitants de Saint-Beno\u00eet seront la priorit\u00e9<\/strong> de ce jeune conseil et feront l\u2019objet d\u2019<strong>une attention bienveillante<\/strong>.<\/p>\n<p>La nouvelle mandature\u00a0d\u00e9bute avec un programme ambitieux. Des <strong>commissions th\u00e9matiques <\/strong>vont rapidement \u00eatre constitu\u00e9es pour entrer dans vif de la concr\u00e9tisation, notamment dans les domaines\u00a0:<br \/>\n\u2013\u00a0\u00a0<strong>Transition Ecologique<\/strong><br \/>\n\u2013\u00a0\u00a0<strong>D\u00e9veloppement Economique<\/strong><br \/>\n\u2013\u00a0\u00a0<strong>Solidarit\u00e9<\/strong>, petite enfance et seniors<br \/>\n\u2013\u00a0\u00a0<strong>S\u00e9curit\u00e9 <\/strong>et la <strong>Tranquillit\u00e9 Publique<\/strong><br \/>\n\u2013\u00a0\u00a0<strong>Vie Culturelle<\/strong> et <strong>Sportive<\/strong>, repr\u00e9sentation de la vie de la commune.<\/p>\n<p>La transparence<strong> <\/strong>et <strong>l\u2019\u00e9coute<\/strong>, traduction de l\u2019<strong>honn\u00eatet\u00e9<\/strong> et de la serviabilit\u00e9 envers les habitants, sont autant de priorit\u00e9s<strong> <\/strong>inscrites dans l\u2019ordre du jour du nouveau maire. Cette \u00e9coute a \u00e9t\u00e9 imagin\u00e9e par Monsieur le Maire, comme un \u00e9change d\u2019id\u00e9es avec les habitants\u00a0:<br \/>\n<strong>\u2013 collectivement<\/strong> tout d\u2019abord, \u00e0 travers la d\u00e9mocratie participative dans chaque quartier, repr\u00e9sent\u00e9e par des jeunes et des plus exp\u00e9riment\u00e9s<br \/>\n\u2013 <strong>individuellement<\/strong> ensuite, par une permanence en mairie le samedi matin.<\/p>\n<p>La <strong>ma\u00eetrise des d\u00e9penses publiques<\/strong> restera une pr\u00e9occupation constante. Chaque euro investi devra profiter <strong>directement aux habitants<\/strong>. Une gestion efficiente nous permettra de <strong>maintenir des services publics de qualit\u00e9<\/strong> et de poursuivre notre dynamique d\u2019investissements. Enfin, cette ambition d\u2019<strong>agir ensemble <\/strong>pour une <strong>ville solidaire<\/strong> et<strong> tourn\u00e9e vers l\u2019avenir<\/strong> ne pourra se concr\u00e9tiser que par l\u2019engagement du personnel communal, sur qui Hubert Bailly et le conseil savent pouvoir compter.<\/p>\n<p>Dans son allocution d\u2019entr\u00e9e, monsieur Hubert Bailly concluait<br \/>\n\u00ab<strong><em>\u00a0Ensemble<\/em><\/strong><em>, nous allons \u00e9crire <strong>une nouvelle et belle page de l\u2019histoire de notre commune<\/strong>.\u00a0<strong>La confiance des habitants nous honore et nous oblige<\/strong><\/em>\u00a0\u00bb.<\/p>\n<p>Ci-dessous, l\u2019ensemble du nouveau Conseil Municipal, le 22 mars 2026. <\/p>\n<p><a href=\"https:\/\/station.illiwap.com\/uploads\/alertes\/documents\/OGPivPS-zWMe3Ucy_FQDRwmXdXDtRT1MAMNY_hjQSR4.jpg\"><\/a><\/p>\n<div style=\"margin-top: 40px;text-align: center\"><a href=\"\/wordpress\/news\/\" class=\"btn-retour-actus\" style=\"padding: 10px 20px;background-color: #eee;color: #333;text-decoration: none;border-radius: 4px;font-weight: bold\">\u2190 Retour aux actualit\u00e9s<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Ensemble, nous allons \u00e9crire une nouvelle et belle page de l\u2019histoire de notre commune.\u00a0\u00bb Dimanche 22 mars 2026, le nouveau Conseil Municipal s\u2019est officiellement install\u00e9.\u00a0M. Hubert Bailly a \u00e9t\u00e9 \u00e9lu maire de la commune de Saint-Beno\u00eet. Huit adjoints, onze d\u00e9l\u00e9gu\u00e9s et neuf conseillers municipaux\u00a0se sont engag\u00e9s pour l\u2019\u00e9pauler dans la conduite des projets de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[223],"tags":[],"class_list":["post-3898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts\/3898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=3898"}],"version-history":[{"count":1,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts\/3898\/revisions"}],"predecessor-version":[{"id":4010,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts\/3898\/revisions\/4010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media\/4009"}],"wp:attachment":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=3898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=3898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=3898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}