{"id":4031,"date":"2026-05-06T08:00:02","date_gmt":"2026-05-06T06:00:02","guid":{"rendered":"https:\/\/saintbenoit86.fr\/wordpress\/delegations-des-elus-et-commissions-communales\/"},"modified":"2026-05-06T08:00:02","modified_gmt":"2026-05-06T06:00:02","slug":"delegations-des-elus-et-commissions-communales","status":"publish","type":"post","link":"https:\/\/saintbenoit86.fr\/wordpress\/delegations-des-elus-et-commissions-communales\/","title":{"rendered":"D\u00e9l\u00e9gations des \u00e9lus et commissions communales"},"content":{"rendered":"<p>\u00ab\u00a0Agissons ensemble pour une ville solidaire et tourn\u00e9e vers l\u2019avenir.\u00a0\u00bb<\/p>\n<p>\n\u00a0<\/p>\n<div style=\"margin-top: 40px;text-align: center\"><a href=\"\/wordpress\/news\/\" class=\"btn-retour-actus\" style=\"padding: 10px 20px;background-color: #eee;color: #333;text-decoration: none;border-radius: 4px;font-weight: bold\">\u2190 Retour aux actualit\u00e9s<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Agissons ensemble pour une ville solidaire et tourn\u00e9e vers l\u2019avenir.\u00a0\u00bb \u00a0 \u2190 Retour aux actualit\u00e9s<\/p>\n","protected":false},"author":0,"featured_media":4032,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[223],"tags":[],"class_list":["post-4031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=4031"}],"version-history":[{"count":0,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media\/4032"}],"wp:attachment":[{"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=4031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=4031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saintbenoit86.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=4031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}